{"id":11409,"date":"2023-09-15T11:15:15","date_gmt":"2023-09-15T09:15:15","guid":{"rendered":"https:\/\/emsaquimica.com\/?p=11409"},"modified":"2024-03-13T11:13:16","modified_gmt":"2024-03-13T10:13:16","slug":"emsa-publie-son-premier-rapport-sur-le-developpment-durable","status":"publish","type":"post","link":"https:\/\/emsaquimica.com\/fr\/2023\/09\/15\/emsa-publie-son-premier-rapport-sur-le-developpment-durable\/","title":{"rendered":"EMSA publie son premier rapport sur le d\u00e9veloppement durable"},"content":{"rendered":"<p>L&rsquo;ann\u00e9e 2022 marque une \u00e9tape importante dans l&rsquo;engagement de l&rsquo;Emsa en faveur du d\u00e9veloppement durable. Au cours de cette p\u00e9riode, nous avons pass\u00e9 en revue, organis\u00e9 et d\u00e9fini nos actions pour \u00e9voluer vers des pratiques plus durables. Notre m\u00e9thodologie repose sur trois piliers essentiels : l&rsquo;identification des questions critiques par le biais d&rsquo;une double analyse de mat\u00e9rialit\u00e9, l&rsquo;orientation des principes de la <a href=\"https:\/\/www.globalreporting.org\/\">Global Reporting Initiative (GRI)<\/a> et l&rsquo;alignement strat\u00e9gique sur les <a href=\"https:\/\/www.un.org\/sustainabledevelopment\/fr\/objectifs-de-developpement-durable\/\">Objectifs de D\u00e9veloppement Durable (ODD)<\/a> des Nations unies. En collaboration avec <a href=\"https:\/\/www.anthesisgroup.com\/\">Anthesis Lavola<\/a>, nous avons men\u00e9 une double analyse de mat\u00e9rialit\u00e9 d\u00e9taill\u00e9e afin d&rsquo;am\u00e9liorer notre gestion durable. En outre, nous nous sommes engag\u00e9s dans l&rsquo;Agenda 2030, en adoptant les ODD des Nations unies.<\/p>\n<p>Chez Emsa, nous sommes fermement d\u00e9termin\u00e9s \u00e0 avoir un impact positif sur les personnes et les secteurs dans lesquels nous op\u00e9rons. Gr\u00e2ce \u00e0 notre objectif \u00ab\u00a0We Care\u00a0\u00bb, qui repr\u00e9sente notre essence, nous lions notre culture d&rsquo;entreprise, nos valeurs, notre mission et nos objectifs pour avancer vers un avenir durable.<\/p>\n<h5><span style=\"color: #62b5e5;\">We Care about world | Environnement:<\/span><\/h5>\n<p>Dans cette section, nous soulignons notre engagement en faveur d&rsquo;une gestion efficace des ressources, d&rsquo;une \u00e9conomie circulaire et d&rsquo;une production et d&rsquo;une consommation responsables. Nous nous effor\u00e7ons de minimiser notre impact sur l&rsquo;environnement gr\u00e2ce \u00e0 des pratiques durables, nous proposons des mati\u00e8res premi\u00e8res g\u00e9r\u00e9es de mani\u00e8re responsable et nous contribuons \u00e0 la pr\u00e9servation de l&rsquo;environnement. En outre, nous participons activement \u00e0 la distribution de produits chimiques r\u00e9pondant \u00e0 des normes durables.<\/p>\n<h5><span style=\"color: #62b5e5;\">We Care about people | Social:<\/span><\/h5>\n<p>Nous abordons ici des questions cl\u00e9s li\u00e9es \u00e0 nos employ\u00e9s et \u00e0 la soci\u00e9t\u00e9. Nous nous engageons \u00e0 assurer la qualit\u00e9 de l&#8217;emploi, des conditions de travail \u00e9quitables, des avantages pour nos employ\u00e9s et \u00e0 fournir des informations claires sur les produits et l&rsquo;\u00e9tiquetage. En outre, nous nous concentrons sur la sant\u00e9, le bien-\u00eatre, la r\u00e9duction des in\u00e9galit\u00e9s et la promotion de l&rsquo;\u00e9galit\u00e9 des sexes et de la diversit\u00e9.<\/p>\n<h5><span style=\"color: #62b5e5;\">We Care about innovation | Gouvernance:<\/span><\/h5>\n<p>Dans cette section, nous soulignons notre sant\u00e9 \u00e9conomique et financi\u00e8re, notre engagement en faveur de la num\u00e9risation et notre engagement en mati\u00e8re de conformit\u00e9 r\u00e9glementaire. Nous recherchons un bon \u00e9quilibre entre le progr\u00e8s \u00e9conomique et la responsabilit\u00e9 de l&rsquo;entreprise.<\/p>\n<p>En r\u00e9sum\u00e9, le rapport sur le d\u00e9veloppement durable 2022 refl\u00e8te notre engagement en faveur du d\u00e9veloppement durable, en abordant les questions environnementales, sociales et de gouvernance. Nous nous engageons pour un avenir plus durable et nous continuerons \u00e0 am\u00e9liorer nos pratiques pour contribuer au bien-\u00eatre de la plan\u00e8te et de la soci\u00e9t\u00e9.<\/p>\n<p>Nous vous invitons \u00e0 lire notre <a href=\"https:\/\/emsaquimica.com\/wp-content\/uploads\/2024\/01\/Memoria-de-Sostenibilidad-2022_29-01-24.pdf\">Rapport sur le D\u00e9veloppement Durable 2022<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Emsa souligne son engagement en faveur du d\u00e9veloppement durable en identifiant les probl\u00e8mes critiques, en adoptant les ODD et en proc\u00e9dant \u00e0 une double analyse de mat\u00e9rialit\u00e9.<\/p>\n","protected":false},"author":4,"featured_media":11651,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[137,102,111],"tags":[],"class_list":["post-11409","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-rsc-fr","category-general-fr","category-sostenibilidad-fr"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>EMSA publie son premier rapport sur le d\u00e9veloppement durable - Emsa<\/title>\n<meta name=\"description\" content=\"D\u00e9couvrez notre engagement de 2022 en faveur du d\u00e9veloppement durable chez Emsa. Guid\u00e9s par les principes de la GRI et les ODD de l&#039;ONU, nous abordons les principales questions environnementales, sociales et de gouvernance en vue d&#039;un avenir plus durable.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/emsaquimica.com\/fr\/2023\/09\/15\/emsa-publie-son-premier-rapport-sur-le-developpment-durable\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"EMSA publie son premier rapport sur le d\u00e9veloppement durable - Emsa\" \/>\n<meta property=\"og:description\" content=\"D\u00e9couvrez notre engagement de 2022 en faveur du d\u00e9veloppement durable chez Emsa. Guid\u00e9s par les principes de la GRI et les ODD de l&#039;ONU, nous abordons les principales questions environnementales, sociales et de gouvernance en vue d&#039;un avenir plus durable.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/emsaquimica.com\/fr\/2023\/09\/15\/emsa-publie-son-premier-rapport-sur-le-developpment-durable\/\" \/>\n<meta property=\"og:site_name\" content=\"Emsa\" \/>\n<meta property=\"article:published_time\" content=\"2023-09-15T09:15:15+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-13T10:13:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/emsaquimica.com\/wp-content\/uploads\/2024\/03\/2022-3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1079\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Luc\u00eda Sendon\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Luc\u00eda Sendon\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/emsaquimica.com\\\/fr\\\/2023\\\/09\\\/15\\\/emsa-publie-son-premier-rapport-sur-le-developpment-durable\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/emsaquimica.com\\\/fr\\\/2023\\\/09\\\/15\\\/emsa-publie-son-premier-rapport-sur-le-developpment-durable\\\/\"},\"author\":{\"name\":\"Luc\u00eda Sendon\",\"@id\":\"https:\\\/\\\/emsaquimica.com\\\/fr\\\/#\\\/schema\\\/person\\\/6220dd4edbe09a20ab455fbdf986da95\"},\"headline\":\"EMSA publie son premier rapport sur le d\u00e9veloppement durable\",\"datePublished\":\"2023-09-15T09:15:15+00:00\",\"dateModified\":\"2024-03-13T10:13:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/emsaquimica.com\\\/fr\\\/2023\\\/09\\\/15\\\/emsa-publie-son-premier-rapport-sur-le-developpment-durable\\\/\"},\"wordCount\":484,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/emsaquimica.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/emsaquimica.com\\\/fr\\\/2023\\\/09\\\/15\\\/emsa-publie-son-premier-rapport-sur-le-developpment-durable\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/emsaquimica.com\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/Memoria-foto-2022.jpg\",\"articleSection\":[\"CSR\",\"GENERAL\",\"SOSTENIBILIDAD\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/emsaquimica.com\\\/fr\\\/2023\\\/09\\\/15\\\/emsa-publie-son-premier-rapport-sur-le-developpment-durable\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/emsaquimica.com\\\/fr\\\/2023\\\/09\\\/15\\\/emsa-publie-son-premier-rapport-sur-le-developpment-durable\\\/\",\"url\":\"https:\\\/\\\/emsaquimica.com\\\/fr\\\/2023\\\/09\\\/15\\\/emsa-publie-son-premier-rapport-sur-le-developpment-durable\\\/\",\"name\":\"EMSA publie son premier rapport sur le d\u00e9veloppement durable - Emsa\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/emsaquimica.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/emsaquimica.com\\\/fr\\\/2023\\\/09\\\/15\\\/emsa-publie-son-premier-rapport-sur-le-developpment-durable\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/emsaquimica.com\\\/fr\\\/2023\\\/09\\\/15\\\/emsa-publie-son-premier-rapport-sur-le-developpment-durable\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/emsaquimica.com\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/Memoria-foto-2022.jpg\",\"datePublished\":\"2023-09-15T09:15:15+00:00\",\"dateModified\":\"2024-03-13T10:13:16+00:00\",\"description\":\"D\u00e9couvrez notre engagement de 2022 en faveur du d\u00e9veloppement durable chez Emsa. Guid\u00e9s par les principes de la GRI et les ODD de l'ONU, nous abordons les principales questions environnementales, sociales et de gouvernance en vue d'un avenir plus durable.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/emsaquimica.com\\\/fr\\\/2023\\\/09\\\/15\\\/emsa-publie-son-premier-rapport-sur-le-developpment-durable\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/emsaquimica.com\\\/fr\\\/2023\\\/09\\\/15\\\/emsa-publie-son-premier-rapport-sur-le-developpment-durable\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/emsaquimica.com\\\/fr\\\/2023\\\/09\\\/15\\\/emsa-publie-son-premier-rapport-sur-le-developpment-durable\\\/#primaryimage\",\"url\":\"https:\\\/\\\/emsaquimica.com\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/Memoria-foto-2022.jpg\",\"contentUrl\":\"https:\\\/\\\/emsaquimica.com\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/Memoria-foto-2022.jpg\",\"width\":1100,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/emsaquimica.com\\\/fr\\\/2023\\\/09\\\/15\\\/emsa-publie-son-premier-rapport-sur-le-developpment-durable\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/emsaquimica.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"EMSA publie son premier rapport sur le d\u00e9veloppement durable\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/emsaquimica.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/emsaquimica.com\\\/fr\\\/\",\"name\":\"Emsa\",\"description\":\"Committed Chemistry\",\"publisher\":{\"@id\":\"https:\\\/\\\/emsaquimica.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/emsaquimica.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/emsaquimica.com\\\/fr\\\/#organization\",\"name\":\"Emsa\",\"url\":\"https:\\\/\\\/emsaquimica.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/emsaquimica.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/emsaquimica.com\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/Logo-Emsa.svg\",\"contentUrl\":\"https:\\\/\\\/emsaquimica.com\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/Logo-Emsa.svg\",\"width\":200,\"height\":50,\"caption\":\"Emsa\"},\"image\":{\"@id\":\"https:\\\/\\\/emsaquimica.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/emsaquimica.com\\\/fr\\\/#\\\/schema\\\/person\\\/6220dd4edbe09a20ab455fbdf986da95\",\"name\":\"Luc\u00eda Sendon\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e1bd500e76aa978f50f4f74edc241e36f14cb7883b817242922ec44be5ec8af5?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e1bd500e76aa978f50f4f74edc241e36f14cb7883b817242922ec44be5ec8af5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e1bd500e76aa978f50f4f74edc241e36f14cb7883b817242922ec44be5ec8af5?s=96&d=mm&r=g\",\"caption\":\"Luc\u00eda Sendon\"},\"url\":\"https:\\\/\\\/emsaquimica.com\\\/fr\\\/author\\\/lsendon\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"EMSA publie son premier rapport sur le d\u00e9veloppement durable - Emsa","description":"D\u00e9couvrez notre engagement de 2022 en faveur du d\u00e9veloppement durable chez Emsa. Guid\u00e9s par les principes de la GRI et les ODD de l'ONU, nous abordons les principales questions environnementales, sociales et de gouvernance en vue d'un avenir plus durable.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/emsaquimica.com\/fr\/2023\/09\/15\/emsa-publie-son-premier-rapport-sur-le-developpment-durable\/","og_locale":"fr_FR","og_type":"article","og_title":"EMSA publie son premier rapport sur le d\u00e9veloppement durable - Emsa","og_description":"D\u00e9couvrez notre engagement de 2022 en faveur du d\u00e9veloppement durable chez Emsa. Guid\u00e9s par les principes de la GRI et les ODD de l'ONU, nous abordons les principales questions environnementales, sociales et de gouvernance en vue d'un avenir plus durable.","og_url":"https:\/\/emsaquimica.com\/fr\/2023\/09\/15\/emsa-publie-son-premier-rapport-sur-le-developpment-durable\/","og_site_name":"Emsa","article_published_time":"2023-09-15T09:15:15+00:00","article_modified_time":"2024-03-13T10:13:16+00:00","og_image":[{"width":1920,"height":1079,"url":"https:\/\/emsaquimica.com\/wp-content\/uploads\/2024\/03\/2022-3.jpg","type":"image\/jpeg"}],"author":"Luc\u00eda Sendon","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Luc\u00eda Sendon","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/emsaquimica.com\/fr\/2023\/09\/15\/emsa-publie-son-premier-rapport-sur-le-developpment-durable\/#article","isPartOf":{"@id":"https:\/\/emsaquimica.com\/fr\/2023\/09\/15\/emsa-publie-son-premier-rapport-sur-le-developpment-durable\/"},"author":{"name":"Luc\u00eda Sendon","@id":"https:\/\/emsaquimica.com\/fr\/#\/schema\/person\/6220dd4edbe09a20ab455fbdf986da95"},"headline":"EMSA publie son premier rapport sur le d\u00e9veloppement durable","datePublished":"2023-09-15T09:15:15+00:00","dateModified":"2024-03-13T10:13:16+00:00","mainEntityOfPage":{"@id":"https:\/\/emsaquimica.com\/fr\/2023\/09\/15\/emsa-publie-son-premier-rapport-sur-le-developpment-durable\/"},"wordCount":484,"commentCount":0,"publisher":{"@id":"https:\/\/emsaquimica.com\/fr\/#organization"},"image":{"@id":"https:\/\/emsaquimica.com\/fr\/2023\/09\/15\/emsa-publie-son-premier-rapport-sur-le-developpment-durable\/#primaryimage"},"thumbnailUrl":"https:\/\/emsaquimica.com\/wp-content\/uploads\/2023\/09\/Memoria-foto-2022.jpg","articleSection":["CSR","GENERAL","SOSTENIBILIDAD"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/emsaquimica.com\/fr\/2023\/09\/15\/emsa-publie-son-premier-rapport-sur-le-developpment-durable\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/emsaquimica.com\/fr\/2023\/09\/15\/emsa-publie-son-premier-rapport-sur-le-developpment-durable\/","url":"https:\/\/emsaquimica.com\/fr\/2023\/09\/15\/emsa-publie-son-premier-rapport-sur-le-developpment-durable\/","name":"EMSA publie son premier rapport sur le d\u00e9veloppement durable - Emsa","isPartOf":{"@id":"https:\/\/emsaquimica.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/emsaquimica.com\/fr\/2023\/09\/15\/emsa-publie-son-premier-rapport-sur-le-developpment-durable\/#primaryimage"},"image":{"@id":"https:\/\/emsaquimica.com\/fr\/2023\/09\/15\/emsa-publie-son-premier-rapport-sur-le-developpment-durable\/#primaryimage"},"thumbnailUrl":"https:\/\/emsaquimica.com\/wp-content\/uploads\/2023\/09\/Memoria-foto-2022.jpg","datePublished":"2023-09-15T09:15:15+00:00","dateModified":"2024-03-13T10:13:16+00:00","description":"D\u00e9couvrez notre engagement de 2022 en faveur du d\u00e9veloppement durable chez Emsa. Guid\u00e9s par les principes de la GRI et les ODD de l'ONU, nous abordons les principales questions environnementales, sociales et de gouvernance en vue d'un avenir plus durable.","breadcrumb":{"@id":"https:\/\/emsaquimica.com\/fr\/2023\/09\/15\/emsa-publie-son-premier-rapport-sur-le-developpment-durable\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/emsaquimica.com\/fr\/2023\/09\/15\/emsa-publie-son-premier-rapport-sur-le-developpment-durable\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/emsaquimica.com\/fr\/2023\/09\/15\/emsa-publie-son-premier-rapport-sur-le-developpment-durable\/#primaryimage","url":"https:\/\/emsaquimica.com\/wp-content\/uploads\/2023\/09\/Memoria-foto-2022.jpg","contentUrl":"https:\/\/emsaquimica.com\/wp-content\/uploads\/2023\/09\/Memoria-foto-2022.jpg","width":1100,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/emsaquimica.com\/fr\/2023\/09\/15\/emsa-publie-son-premier-rapport-sur-le-developpment-durable\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/emsaquimica.com\/fr\/"},{"@type":"ListItem","position":2,"name":"EMSA publie son premier rapport sur le d\u00e9veloppement durable"}]},{"@type":"WebSite","@id":"https:\/\/emsaquimica.com\/fr\/#website","url":"https:\/\/emsaquimica.com\/fr\/","name":"Emsa","description":"Committed Chemistry","publisher":{"@id":"https:\/\/emsaquimica.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/emsaquimica.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/emsaquimica.com\/fr\/#organization","name":"Emsa","url":"https:\/\/emsaquimica.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/emsaquimica.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/emsaquimica.com\/wp-content\/uploads\/2021\/11\/Logo-Emsa.svg","contentUrl":"https:\/\/emsaquimica.com\/wp-content\/uploads\/2021\/11\/Logo-Emsa.svg","width":200,"height":50,"caption":"Emsa"},"image":{"@id":"https:\/\/emsaquimica.com\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/emsaquimica.com\/fr\/#\/schema\/person\/6220dd4edbe09a20ab455fbdf986da95","name":"Luc\u00eda Sendon","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/e1bd500e76aa978f50f4f74edc241e36f14cb7883b817242922ec44be5ec8af5?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e1bd500e76aa978f50f4f74edc241e36f14cb7883b817242922ec44be5ec8af5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e1bd500e76aa978f50f4f74edc241e36f14cb7883b817242922ec44be5ec8af5?s=96&d=mm&r=g","caption":"Luc\u00eda Sendon"},"url":"https:\/\/emsaquimica.com\/fr\/author\/lsendon\/"}]}},"_links":{"self":[{"href":"https:\/\/emsaquimica.com\/fr\/wp-json\/wp\/v2\/posts\/11409","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/emsaquimica.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/emsaquimica.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/emsaquimica.com\/fr\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/emsaquimica.com\/fr\/wp-json\/wp\/v2\/comments?post=11409"}],"version-history":[{"count":5,"href":"https:\/\/emsaquimica.com\/fr\/wp-json\/wp\/v2\/posts\/11409\/revisions"}],"predecessor-version":[{"id":11422,"href":"https:\/\/emsaquimica.com\/fr\/wp-json\/wp\/v2\/posts\/11409\/revisions\/11422"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/emsaquimica.com\/fr\/wp-json\/wp\/v2\/media\/11651"}],"wp:attachment":[{"href":"https:\/\/emsaquimica.com\/fr\/wp-json\/wp\/v2\/media?parent=11409"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/emsaquimica.com\/fr\/wp-json\/wp\/v2\/categories?post=11409"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/emsaquimica.com\/fr\/wp-json\/wp\/v2\/tags?post=11409"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}