{"id":14845,"date":"2025-11-06T17:15:48","date_gmt":"2025-11-06T16:15:48","guid":{"rendered":"https:\/\/emsaquimica.com\/?p=14845"},"modified":"2025-11-06T17:24:51","modified_gmt":"2025-11-06T16:24:51","slug":"emsa-entra-na-fase-2-do-registro-de-pegada-de-carbono-do-miteco","status":"publish","type":"post","link":"https:\/\/emsaquimica.com\/pt-pt\/2025\/11\/06\/emsa-entra-na-fase-2-do-registro-de-pegada-de-carbono-do-miteco\/","title":{"rendered":"EMSA entra na Fase 2 do Registro de Pegada de Carbono do MITECO"},"content":{"rendered":"<p data-start=\"71\" data-end=\"421\">Na Emsa Tecnolog\u00eda Qu\u00edmica, continuamos avan\u00e7ando em nosso compromisso com a sustentabilidade e a redu\u00e7\u00e3o das emiss\u00f5es. Ap\u00f3s a inscri\u00e7\u00e3o na Fase 1 (C\u00e1lculo) do <em data-start=\"231\" data-end=\"305\">Registro de Pegada de Carbono, Compensa\u00e7\u00e3o e Projetos de Absor\u00e7\u00e3o de CO\u2082<\/em> do <a href=\"https:\/\/www.miteco.gob.es\/es.html\"><em data-start=\"309\" data-end=\"372\">Minist\u00e9rio para a Transi\u00e7\u00e3o Ecol\u00f3gica e o Desafio Demogr\u00e1fico<\/em><\/a> (MITECO), alcan\u00e7amos agora a <strong><a href=\"https:\/\/www.miteco.gob.es\/es\/cambio-climatico\/temas\/registro-huella.html\">Fase 2: <em data-start=\"410\" data-end=\"418\">Reduzo<\/em>.<\/a><\/strong><\/p>\n<p data-start=\"423\" data-end=\"743\">Esta distin\u00e7\u00e3o comprova que a Emsa n\u00e3o apenas calcula sua pegada de carbono de acordo com os crit\u00e9rios oficiais do MITECO, mas tamb\u00e9m<strong> implementa medidas eficazes para reduzir suas emiss\u00f5es de gases de efeito estufa<\/strong>. O c\u00e1lculo inclui exclusivamente as emiss\u00f5es de Escopo 1 e 2, conforme os crit\u00e9rios oficiais do MITECO.<\/p>\n<p data-start=\"745\" data-end=\"985\">O Registro de Pegada de Carbono identifica as organiza\u00e7\u00f5es que atuam de forma respons\u00e1vel diante das mudan\u00e7as clim\u00e1ticas e reconhece aquelas que, como a Emsa, avan\u00e7am em dire\u00e7\u00e3o a uma gest\u00e3o mais eficiente e sustent\u00e1vel de seus processos.<\/p>\n<p data-start=\"987\" data-end=\"1180\">Este novo marco reflete nosso compromisso com o pilar ambiental do <strong>plano <em data-start=\"1060\" data-end=\"1069\">We Care<\/em><\/strong>, voltado para minimizar o impacto ambiental e contribuir ativamente para a descarboniza\u00e7\u00e3o do setor qu\u00edmico.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Emsa d\u00e1 mais um passo em seu compromisso clim\u00e1tico ao alcan\u00e7ar a Fase 2 (Reduzo) do registro oficial de pegada de carbono do MITECO.<\/p>\n","protected":false},"author":12,"featured_media":14839,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[104,114],"tags":[],"class_list":["post-14845","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-general-pt-pt","category-sostenibilidad-pt-pt"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>EMSA entra na Fase 2 do Registro de Pegada de Carbono do MITECO - Emsa<\/title>\n<meta name=\"description\" content=\"Emsa Tecnolog\u00eda Qu\u00edmica alcan\u00e7a a Fase 2 (Reduzo) do Registro de Pegada de Carbono do MITECO, refor\u00e7ando seu compromisso com a redu\u00e7\u00e3o das emiss\u00f5es.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/emsaquimica.com\/pt-pt\/2025\/11\/06\/emsa-entra-na-fase-2-do-registro-de-pegada-de-carbono-do-miteco\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"EMSA entra na Fase 2 do Registro de Pegada de Carbono do MITECO - Emsa\" \/>\n<meta property=\"og:description\" content=\"Emsa Tecnolog\u00eda Qu\u00edmica alcan\u00e7a a Fase 2 (Reduzo) do Registro de Pegada de Carbono do MITECO, refor\u00e7ando seu compromisso com a redu\u00e7\u00e3o das emiss\u00f5es.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/emsaquimica.com\/pt-pt\/2025\/11\/06\/emsa-entra-na-fase-2-do-registro-de-pegada-de-carbono-do-miteco\/\" \/>\n<meta property=\"og:site_name\" content=\"Emsa\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-06T16:15:48+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-06T16:24:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/emsaquimica.com\/wp-content\/uploads\/2025\/11\/MITECO_-blog-1-1024x704.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"704\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Marina Gimenez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Marina Gimenez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/emsaquimica.com\\\/pt-pt\\\/2025\\\/11\\\/06\\\/emsa-entra-na-fase-2-do-registro-de-pegada-de-carbono-do-miteco\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/emsaquimica.com\\\/pt-pt\\\/2025\\\/11\\\/06\\\/emsa-entra-na-fase-2-do-registro-de-pegada-de-carbono-do-miteco\\\/\"},\"author\":{\"name\":\"Marina Gimenez\",\"@id\":\"https:\\\/\\\/emsaquimica.com\\\/pt-pt\\\/#\\\/schema\\\/person\\\/427369c3666537b67fa259fbe589383e\"},\"headline\":\"EMSA entra na Fase 2 do Registro de Pegada de Carbono do MITECO\",\"datePublished\":\"2025-11-06T16:15:48+00:00\",\"dateModified\":\"2025-11-06T16:24:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/emsaquimica.com\\\/pt-pt\\\/2025\\\/11\\\/06\\\/emsa-entra-na-fase-2-do-registro-de-pegada-de-carbono-do-miteco\\\/\"},\"wordCount\":214,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/emsaquimica.com\\\/pt-pt\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/emsaquimica.com\\\/pt-pt\\\/2025\\\/11\\\/06\\\/emsa-entra-na-fase-2-do-registro-de-pegada-de-carbono-do-miteco\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/emsaquimica.com\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/MITECO_-blog-1.png\",\"articleSection\":[\"GENERAL\",\"SOSTENIBILIDAD\"],\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/emsaquimica.com\\\/pt-pt\\\/2025\\\/11\\\/06\\\/emsa-entra-na-fase-2-do-registro-de-pegada-de-carbono-do-miteco\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/emsaquimica.com\\\/pt-pt\\\/2025\\\/11\\\/06\\\/emsa-entra-na-fase-2-do-registro-de-pegada-de-carbono-do-miteco\\\/\",\"url\":\"https:\\\/\\\/emsaquimica.com\\\/pt-pt\\\/2025\\\/11\\\/06\\\/emsa-entra-na-fase-2-do-registro-de-pegada-de-carbono-do-miteco\\\/\",\"name\":\"EMSA entra na Fase 2 do Registro de Pegada de Carbono do MITECO - Emsa\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/emsaquimica.com\\\/pt-pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/emsaquimica.com\\\/pt-pt\\\/2025\\\/11\\\/06\\\/emsa-entra-na-fase-2-do-registro-de-pegada-de-carbono-do-miteco\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/emsaquimica.com\\\/pt-pt\\\/2025\\\/11\\\/06\\\/emsa-entra-na-fase-2-do-registro-de-pegada-de-carbono-do-miteco\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/emsaquimica.com\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/MITECO_-blog-1.png\",\"datePublished\":\"2025-11-06T16:15:48+00:00\",\"dateModified\":\"2025-11-06T16:24:51+00:00\",\"description\":\"Emsa Tecnolog\u00eda Qu\u00edmica alcan\u00e7a a Fase 2 (Reduzo) do Registro de Pegada de Carbono do MITECO, refor\u00e7ando seu compromisso com a redu\u00e7\u00e3o das emiss\u00f5es.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/emsaquimica.com\\\/pt-pt\\\/2025\\\/11\\\/06\\\/emsa-entra-na-fase-2-do-registro-de-pegada-de-carbono-do-miteco\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/emsaquimica.com\\\/pt-pt\\\/2025\\\/11\\\/06\\\/emsa-entra-na-fase-2-do-registro-de-pegada-de-carbono-do-miteco\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/emsaquimica.com\\\/pt-pt\\\/2025\\\/11\\\/06\\\/emsa-entra-na-fase-2-do-registro-de-pegada-de-carbono-do-miteco\\\/#primaryimage\",\"url\":\"https:\\\/\\\/emsaquimica.com\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/MITECO_-blog-1.png\",\"contentUrl\":\"https:\\\/\\\/emsaquimica.com\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/MITECO_-blog-1.png\",\"width\":1600,\"height\":1100},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/emsaquimica.com\\\/pt-pt\\\/2025\\\/11\\\/06\\\/emsa-entra-na-fase-2-do-registro-de-pegada-de-carbono-do-miteco\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/emsaquimica.com\\\/pt-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"EMSA entra na Fase 2 do Registro de Pegada de Carbono do MITECO\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/emsaquimica.com\\\/pt-pt\\\/#website\",\"url\":\"https:\\\/\\\/emsaquimica.com\\\/pt-pt\\\/\",\"name\":\"Emsa\",\"description\":\"Committed Chemistry\",\"publisher\":{\"@id\":\"https:\\\/\\\/emsaquimica.com\\\/pt-pt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/emsaquimica.com\\\/pt-pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/emsaquimica.com\\\/pt-pt\\\/#organization\",\"name\":\"Emsa\",\"url\":\"https:\\\/\\\/emsaquimica.com\\\/pt-pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/emsaquimica.com\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/emsaquimica.com\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/Logo-Emsa.svg\",\"contentUrl\":\"https:\\\/\\\/emsaquimica.com\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/Logo-Emsa.svg\",\"width\":200,\"height\":50,\"caption\":\"Emsa\"},\"image\":{\"@id\":\"https:\\\/\\\/emsaquimica.com\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/emsaquimica.com\\\/pt-pt\\\/#\\\/schema\\\/person\\\/427369c3666537b67fa259fbe589383e\",\"name\":\"Marina Gimenez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7365793a639fec663494da5659c4827908ce37ec91282bd0a3e1d40c78193cd3?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7365793a639fec663494da5659c4827908ce37ec91282bd0a3e1d40c78193cd3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7365793a639fec663494da5659c4827908ce37ec91282bd0a3e1d40c78193cd3?s=96&d=mm&r=g\",\"caption\":\"Marina Gimenez\"},\"url\":\"https:\\\/\\\/emsaquimica.com\\\/pt-pt\\\/author\\\/mgimenezemsaquimica-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"EMSA entra na Fase 2 do Registro de Pegada de Carbono do MITECO - Emsa","description":"Emsa Tecnolog\u00eda Qu\u00edmica alcan\u00e7a a Fase 2 (Reduzo) do Registro de Pegada de Carbono do MITECO, refor\u00e7ando seu compromisso com a redu\u00e7\u00e3o das emiss\u00f5es.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/emsaquimica.com\/pt-pt\/2025\/11\/06\/emsa-entra-na-fase-2-do-registro-de-pegada-de-carbono-do-miteco\/","og_locale":"pt_PT","og_type":"article","og_title":"EMSA entra na Fase 2 do Registro de Pegada de Carbono do MITECO - Emsa","og_description":"Emsa Tecnolog\u00eda Qu\u00edmica alcan\u00e7a a Fase 2 (Reduzo) do Registro de Pegada de Carbono do MITECO, refor\u00e7ando seu compromisso com a redu\u00e7\u00e3o das emiss\u00f5es.","og_url":"https:\/\/emsaquimica.com\/pt-pt\/2025\/11\/06\/emsa-entra-na-fase-2-do-registro-de-pegada-de-carbono-do-miteco\/","og_site_name":"Emsa","article_published_time":"2025-11-06T16:15:48+00:00","article_modified_time":"2025-11-06T16:24:51+00:00","og_image":[{"width":1024,"height":704,"url":"https:\/\/emsaquimica.com\/wp-content\/uploads\/2025\/11\/MITECO_-blog-1-1024x704.png","type":"image\/png"}],"author":"Marina Gimenez","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Marina Gimenez","Tempo estimado de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/emsaquimica.com\/pt-pt\/2025\/11\/06\/emsa-entra-na-fase-2-do-registro-de-pegada-de-carbono-do-miteco\/#article","isPartOf":{"@id":"https:\/\/emsaquimica.com\/pt-pt\/2025\/11\/06\/emsa-entra-na-fase-2-do-registro-de-pegada-de-carbono-do-miteco\/"},"author":{"name":"Marina Gimenez","@id":"https:\/\/emsaquimica.com\/pt-pt\/#\/schema\/person\/427369c3666537b67fa259fbe589383e"},"headline":"EMSA entra na Fase 2 do Registro de Pegada de Carbono do MITECO","datePublished":"2025-11-06T16:15:48+00:00","dateModified":"2025-11-06T16:24:51+00:00","mainEntityOfPage":{"@id":"https:\/\/emsaquimica.com\/pt-pt\/2025\/11\/06\/emsa-entra-na-fase-2-do-registro-de-pegada-de-carbono-do-miteco\/"},"wordCount":214,"commentCount":0,"publisher":{"@id":"https:\/\/emsaquimica.com\/pt-pt\/#organization"},"image":{"@id":"https:\/\/emsaquimica.com\/pt-pt\/2025\/11\/06\/emsa-entra-na-fase-2-do-registro-de-pegada-de-carbono-do-miteco\/#primaryimage"},"thumbnailUrl":"https:\/\/emsaquimica.com\/wp-content\/uploads\/2025\/11\/MITECO_-blog-1.png","articleSection":["GENERAL","SOSTENIBILIDAD"],"inLanguage":"pt-PT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/emsaquimica.com\/pt-pt\/2025\/11\/06\/emsa-entra-na-fase-2-do-registro-de-pegada-de-carbono-do-miteco\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/emsaquimica.com\/pt-pt\/2025\/11\/06\/emsa-entra-na-fase-2-do-registro-de-pegada-de-carbono-do-miteco\/","url":"https:\/\/emsaquimica.com\/pt-pt\/2025\/11\/06\/emsa-entra-na-fase-2-do-registro-de-pegada-de-carbono-do-miteco\/","name":"EMSA entra na Fase 2 do Registro de Pegada de Carbono do MITECO - Emsa","isPartOf":{"@id":"https:\/\/emsaquimica.com\/pt-pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/emsaquimica.com\/pt-pt\/2025\/11\/06\/emsa-entra-na-fase-2-do-registro-de-pegada-de-carbono-do-miteco\/#primaryimage"},"image":{"@id":"https:\/\/emsaquimica.com\/pt-pt\/2025\/11\/06\/emsa-entra-na-fase-2-do-registro-de-pegada-de-carbono-do-miteco\/#primaryimage"},"thumbnailUrl":"https:\/\/emsaquimica.com\/wp-content\/uploads\/2025\/11\/MITECO_-blog-1.png","datePublished":"2025-11-06T16:15:48+00:00","dateModified":"2025-11-06T16:24:51+00:00","description":"Emsa Tecnolog\u00eda Qu\u00edmica alcan\u00e7a a Fase 2 (Reduzo) do Registro de Pegada de Carbono do MITECO, refor\u00e7ando seu compromisso com a redu\u00e7\u00e3o das emiss\u00f5es.","breadcrumb":{"@id":"https:\/\/emsaquimica.com\/pt-pt\/2025\/11\/06\/emsa-entra-na-fase-2-do-registro-de-pegada-de-carbono-do-miteco\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/emsaquimica.com\/pt-pt\/2025\/11\/06\/emsa-entra-na-fase-2-do-registro-de-pegada-de-carbono-do-miteco\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/emsaquimica.com\/pt-pt\/2025\/11\/06\/emsa-entra-na-fase-2-do-registro-de-pegada-de-carbono-do-miteco\/#primaryimage","url":"https:\/\/emsaquimica.com\/wp-content\/uploads\/2025\/11\/MITECO_-blog-1.png","contentUrl":"https:\/\/emsaquimica.com\/wp-content\/uploads\/2025\/11\/MITECO_-blog-1.png","width":1600,"height":1100},{"@type":"BreadcrumbList","@id":"https:\/\/emsaquimica.com\/pt-pt\/2025\/11\/06\/emsa-entra-na-fase-2-do-registro-de-pegada-de-carbono-do-miteco\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/emsaquimica.com\/pt-pt\/"},{"@type":"ListItem","position":2,"name":"EMSA entra na Fase 2 do Registro de Pegada de Carbono do MITECO"}]},{"@type":"WebSite","@id":"https:\/\/emsaquimica.com\/pt-pt\/#website","url":"https:\/\/emsaquimica.com\/pt-pt\/","name":"Emsa","description":"Committed Chemistry","publisher":{"@id":"https:\/\/emsaquimica.com\/pt-pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/emsaquimica.com\/pt-pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/emsaquimica.com\/pt-pt\/#organization","name":"Emsa","url":"https:\/\/emsaquimica.com\/pt-pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/emsaquimica.com\/pt-pt\/#\/schema\/logo\/image\/","url":"https:\/\/emsaquimica.com\/wp-content\/uploads\/2021\/11\/Logo-Emsa.svg","contentUrl":"https:\/\/emsaquimica.com\/wp-content\/uploads\/2021\/11\/Logo-Emsa.svg","width":200,"height":50,"caption":"Emsa"},"image":{"@id":"https:\/\/emsaquimica.com\/pt-pt\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/emsaquimica.com\/pt-pt\/#\/schema\/person\/427369c3666537b67fa259fbe589383e","name":"Marina Gimenez","image":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/secure.gravatar.com\/avatar\/7365793a639fec663494da5659c4827908ce37ec91282bd0a3e1d40c78193cd3?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7365793a639fec663494da5659c4827908ce37ec91282bd0a3e1d40c78193cd3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7365793a639fec663494da5659c4827908ce37ec91282bd0a3e1d40c78193cd3?s=96&d=mm&r=g","caption":"Marina Gimenez"},"url":"https:\/\/emsaquimica.com\/pt-pt\/author\/mgimenezemsaquimica-com\/"}]}},"_links":{"self":[{"href":"https:\/\/emsaquimica.com\/pt-pt\/wp-json\/wp\/v2\/posts\/14845","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/emsaquimica.com\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/emsaquimica.com\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/emsaquimica.com\/pt-pt\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/emsaquimica.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=14845"}],"version-history":[{"count":1,"href":"https:\/\/emsaquimica.com\/pt-pt\/wp-json\/wp\/v2\/posts\/14845\/revisions"}],"predecessor-version":[{"id":14846,"href":"https:\/\/emsaquimica.com\/pt-pt\/wp-json\/wp\/v2\/posts\/14845\/revisions\/14846"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/emsaquimica.com\/pt-pt\/wp-json\/wp\/v2\/media\/14839"}],"wp:attachment":[{"href":"https:\/\/emsaquimica.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=14845"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/emsaquimica.com\/pt-pt\/wp-json\/wp\/v2\/categories?post=14845"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/emsaquimica.com\/pt-pt\/wp-json\/wp\/v2\/tags?post=14845"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}